{"id":110226,"date":"2022-02-05T23:05:53","date_gmt":"2022-02-05T21:05:53","guid":{"rendered":"https:\/\/lossoldaditosdeplomo.com\/?p=110226"},"modified":"2022-02-17T10:26:19","modified_gmt":"2022-02-17T08:26:19","slug":"fabricacion-de-gabiones","status":"publish","type":"post","link":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/","title":{"rendered":"FABRICACI\u00d3N DE GABIONES"},"content":{"rendered":"\n<p>AUTOR: Juan Carlos Santiago Guinea<\/p>\n\n\n\n<p>GABIONES.    Fortificaciones de campa\u00f1a.Remontandose su uso al 3000 ADC y siendo inicialmente aplicado en construcciones de arquitectura civil, el empleo de los gabiones (*) como elementos de protecci\u00f3n militar de la artilleria en campa\u00f1a como en fortificaciones defensivas o de asedio comienza a hacerse extensivo con la llegada de la p\u00f3lvora y de las armas de fuego al arsenal de los ej\u00e9rcitos europeos.Desde comienzos del siglo XV hasta la primera guerra mundial existe informaci\u00f3n constatando su uso como elemento de f\u00e1cil obtenci\u00f3n con los recursos que proporciona el terreno.De forma circular o tronco c\u00f3nica y de diferentes tama\u00f1os , se constata su presencia en grabados , litograf\u00edas y fotograf\u00edas en todo conflicto militar.La realizaci\u00f3n artesanal a escala de un gabion no entra\u00f1a una dificultad especial y puede hacerse con elementos simples que tenemos todos en casa.Mondadientes , cuerda o alambre de esta\u00f1o o de cobre , un poco de plastelina y arena o grava fina es todo lo que necesitaremos.En las fotograf\u00edas siguientes puede verse el proceso de construcci\u00f3n, imprimaci\u00f3n y sellado de huecos para poder confeccionar un molde y realizar copias en serie con resina de poliuretano.Como elemento de escenificacion acompa\u00f1ando a una figura o como parte de una vi\u00f1eta o diorama m\u00e1s complejo es un cl\u00e1sico totalmente recomendable.Os animo a probarlo y espero disfrut\u00e9is como yo.(*) : Del italiano &#8220;gabbione&#8221; o jaula grande.<\/p>\n\n\n\n<p>GABIONS.    Field fortifications.Dating back to 3000 ADC and being initially applied in civil architecture constructions, the use of gabions (*) as elements of military protection for the artillery in the war field as well as in defensive or siege fortifications began to become extensive with the arrival of the gunpowder and firearms to the arsenal of European armies.From the beginning of the XVth C. until the WW1 there exist a lot of information confirming its use as a defensive item which can be easily built with the resources provided by the land. Tree branches and fascines.With a circular shape and in different sizes, the fascine gabions can be seen in engravings, lithographs and photographs in almost all military actions during the last 500 years.The craftsmanship of a scale model gabion is not difficult at all and can be easily done with some simple elements that we all have at home.Toothpicks, thin rope or rigging thread, or even tin or copper wire with some clay and sand or fine gravel is all that we need.In the following photographs you can see the process of construction, priming and sealing of gaps to make a silicone mould and the copies with urethane resin.As a scenery element beside a figure or as part of a more complex vignette or diorama, it is a fully recommended classic item in your collection that you can not miss.I encourage you to try it and I hope you will enjoy it as much as I did.(*) GABION : From the Italian &#8220;gabbione&#8221; or large cage.<\/p>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\"><\/div>\n<\/div>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"239\" data-id=\"110366\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n-300x239.jpg?v=1645086014\" alt=\"\" class=\"wp-image-110366\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n-300x239.jpg?v=1645086014 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n.jpg?v=1645086014 520w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"265\" data-id=\"110381\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272901948_5071591172884925_7853643493674557094_n-300x265.jpg?v=1645086053\" alt=\"\" class=\"wp-image-110381\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272901948_5071591172884925_7853643493674557094_n-300x265.jpg?v=1645086053 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272901948_5071591172884925_7853643493674557094_n-768x678.jpg?v=1645086053 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272901948_5071591172884925_7853643493674557094_n-scaled.jpg?v=1645086053 800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"288\" height=\"175\" data-id=\"110364\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272957635_5071613396216036_3757674933430459752_n.jpg\" alt=\"\" class=\"wp-image-110364\"\/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" data-id=\"110362\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273036507_5071613716216004_4798570297459476766_n-300x200.jpg?v=1645086008\" alt=\"\" class=\"wp-image-110362\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273036507_5071613716216004_4798570297459476766_n-300x200.jpg?v=1645086008 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273036507_5071613716216004_4798570297459476766_n.jpg?v=1645086008 735w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"231\" data-id=\"110361\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272935164_5071614782882564_2314963675755341042_n-300x231.jpg?v=1645086006\" alt=\"\" class=\"wp-image-110361\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272935164_5071614782882564_2314963675755341042_n-300x231.jpg?v=1645086006 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272935164_5071614782882564_2314963675755341042_n-768x590.jpg?v=1645086006 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272935164_5071614782882564_2314963675755341042_n-1536x1181.jpg?v=1645086006 1536w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272935164_5071614782882564_2314963675755341042_n-1200x922.jpg?v=1645086006 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272935164_5071614782882564_2314963675755341042_n-scaled.jpg?v=1645086006 800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"240\" data-id=\"110363\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272960193_5071613559549353_3106916238709029533_n-300x240.jpg?v=1645086010\" alt=\"\" class=\"wp-image-110363\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272960193_5071613559549353_3106916238709029533_n-300x240.jpg?v=1645086010 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272960193_5071613559549353_3106916238709029533_n.jpg?v=1645086010 512w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"219\" data-id=\"110365\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272944045_5071613066216069_789231130151425775_n-300x219.jpg?v=1645086013\" alt=\"\" class=\"wp-image-110365\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272944045_5071613066216069_789231130151425775_n-300x219.jpg?v=1645086013 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272944045_5071613066216069_789231130151425775_n.jpg?v=1645086013 400w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"159\" height=\"300\" data-id=\"110380\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272900020_5071593969551312_7174065586994899349_n-159x300.jpg?v=1645086051\" alt=\"\" class=\"wp-image-110380\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272900020_5071593969551312_7174065586994899349_n-159x300.jpg?v=1645086051 159w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272900020_5071593969551312_7174065586994899349_n-768x1448.jpg?v=1645086051 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272900020_5071593969551312_7174065586994899349_n-815x1536.jpg?v=1645086051 815w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272900020_5071593969551312_7174065586994899349_n-scaled.jpg?v=1645086051 424w\" sizes=\"auto, (max-width: 159px) 85vw, 159px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"187\" height=\"300\" data-id=\"110379\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272953514_5071594052884637_7457647059606075201_n-187x300.jpg?v=1645086049\" alt=\"\" class=\"wp-image-110379\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272953514_5071594052884637_7457647059606075201_n-187x300.jpg?v=1645086049 187w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272953514_5071594052884637_7457647059606075201_n-768x1233.jpg?v=1645086049 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272953514_5071594052884637_7457647059606075201_n-957x1536.jpg?v=1645086049 957w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272953514_5071594052884637_7457647059606075201_n-1200x1926.jpg?v=1645086049 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272953514_5071594052884637_7457647059606075201_n-scaled.jpg?v=1645086049 498w\" sizes=\"auto, (max-width: 187px) 85vw, 187px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"208\" height=\"300\" data-id=\"110378\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273299531_5071595109551198_2460009279838235887_n-208x300.jpg?v=1645086046\" alt=\"\" class=\"wp-image-110378\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273299531_5071595109551198_2460009279838235887_n-208x300.jpg?v=1645086046 208w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273299531_5071595109551198_2460009279838235887_n-768x1105.jpg?v=1645086046 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273299531_5071595109551198_2460009279838235887_n-1067x1536.jpg?v=1645086046 1067w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273299531_5071595109551198_2460009279838235887_n-scaled.jpg?v=1645086046 556w\" sizes=\"auto, (max-width: 208px) 85vw, 208px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"267\" height=\"300\" data-id=\"110377\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272992602_5071595232884519_2332038819932835242_n-267x300.jpg?v=1645086044\" alt=\"\" class=\"wp-image-110377\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272992602_5071595232884519_2332038819932835242_n-267x300.jpg?v=1645086044 267w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272992602_5071595232884519_2332038819932835242_n-768x864.jpg?v=1645086044 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272992602_5071595232884519_2332038819932835242_n-1365x1536.jpg?v=1645086044 1365w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272992602_5071595232884519_2332038819932835242_n-1200x1350.jpg?v=1645086044 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272992602_5071595232884519_2332038819932835242_n-scaled.jpg?v=1645086044 711w\" sizes=\"auto, (max-width: 267px) 85vw, 267px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"179\" data-id=\"110376\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908766_5071595356217840_4406073721059125074_n-300x179.jpg?v=1645086041\" alt=\"\" class=\"wp-image-110376\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908766_5071595356217840_4406073721059125074_n-300x179.jpg?v=1645086041 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908766_5071595356217840_4406073721059125074_n-768x457.jpg?v=1645086041 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908766_5071595356217840_4406073721059125074_n-1536x914.jpg?v=1645086041 1536w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908766_5071595356217840_4406073721059125074_n-1200x714.jpg?v=1645086041 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908766_5071595356217840_4406073721059125074_n-scaled.jpg?v=1645086041 800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"183\" height=\"300\" data-id=\"110375\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273002353_5071595419551167_2452511571351118035_n-183x300.jpg?v=1645086038\" alt=\"\" class=\"wp-image-110375\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273002353_5071595419551167_2452511571351118035_n-183x300.jpg?v=1645086038 183w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273002353_5071595419551167_2452511571351118035_n-768x1260.jpg?v=1645086038 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273002353_5071595419551167_2452511571351118035_n-936x1536.jpg?v=1645086038 936w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/273002353_5071595419551167_2452511571351118035_n-scaled.jpg?v=1645086038 488w\" sizes=\"auto, (max-width: 183px) 85vw, 183px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"254\" data-id=\"110374\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272951797_5071595476217828_6298917937358165176_n-300x254.jpg?v=1645086036\" alt=\"\" class=\"wp-image-110374\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272951797_5071595476217828_6298917937358165176_n-300x254.jpg?v=1645086036 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272951797_5071595476217828_6298917937358165176_n-768x651.jpg?v=1645086036 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272951797_5071595476217828_6298917937358165176_n-1536x1302.jpg?v=1645086036 1536w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272951797_5071595476217828_6298917937358165176_n-1200x1018.jpg?v=1645086036 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272951797_5071595476217828_6298917937358165176_n-scaled.jpg?v=1645086036 800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"175\" data-id=\"110373\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272910167_5071595586217817_6731095292942179833_n-300x175.jpg?v=1645086033\" alt=\"\" class=\"wp-image-110373\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272910167_5071595586217817_6731095292942179833_n-300x175.jpg?v=1645086033 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272910167_5071595586217817_6731095292942179833_n-768x448.jpg?v=1645086033 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272910167_5071595586217817_6731095292942179833_n-1536x896.jpg?v=1645086033 1536w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272910167_5071595586217817_6731095292942179833_n-1200x700.jpg?v=1645086033 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272910167_5071595586217817_6731095292942179833_n-scaled.jpg?v=1645086033 800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"135\" data-id=\"110367\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272954928_5071596552884387_2385185614892516995_n-300x135.jpg?v=1645086017\" alt=\"\" class=\"wp-image-110367\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272954928_5071596552884387_2385185614892516995_n-300x135.jpg?v=1645086017 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272954928_5071596552884387_2385185614892516995_n-768x346.jpg?v=1645086017 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272954928_5071596552884387_2385185614892516995_n-1536x692.jpg?v=1645086017 1536w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272954928_5071596552884387_2385185614892516995_n-1200x540.jpg?v=1645086017 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272954928_5071596552884387_2385185614892516995_n-scaled.jpg?v=1645086017 800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"202\" data-id=\"110372\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272919214_5071595679551141_3643649654054904591_n-300x202.jpg?v=1645086031\" alt=\"\" class=\"wp-image-110372\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272919214_5071595679551141_3643649654054904591_n-300x202.jpg?v=1645086031 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272919214_5071595679551141_3643649654054904591_n-768x517.jpg?v=1645086031 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272919214_5071595679551141_3643649654054904591_n-1536x1034.jpg?v=1645086031 1536w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272919214_5071595679551141_3643649654054904591_n-1200x807.jpg?v=1645086031 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272919214_5071595679551141_3643649654054904591_n-scaled.jpg?v=1645086031 800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"274\" data-id=\"110368\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272880580_5071596426217733_1046271238912812948_n-300x274.jpg?v=1645086020\" alt=\"\" class=\"wp-image-110368\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272880580_5071596426217733_1046271238912812948_n-300x274.jpg?v=1645086020 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272880580_5071596426217733_1046271238912812948_n-768x702.jpg?v=1645086020 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272880580_5071596426217733_1046271238912812948_n-1536x1403.jpg?v=1645086020 1536w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272880580_5071596426217733_1046271238912812948_n-1200x1096.jpg?v=1645086020 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272880580_5071596426217733_1046271238912812948_n-scaled.jpg?v=1645086020 800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"196\" data-id=\"110369\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908930_5071596319551077_3812450406687515297_n-300x196.jpg?v=1645086022\" alt=\"\" class=\"wp-image-110369\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908930_5071596319551077_3812450406687515297_n-300x196.jpg?v=1645086022 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908930_5071596319551077_3812450406687515297_n-768x501.jpg?v=1645086022 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908930_5071596319551077_3812450406687515297_n-1536x1002.jpg?v=1645086022 1536w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908930_5071596319551077_3812450406687515297_n-1200x783.jpg?v=1645086022 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272908930_5071596319551077_3812450406687515297_n-scaled.jpg?v=1645086022 800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"242\" data-id=\"110370\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272979172_5071596162884426_4731551265188371262_n-300x242.jpg?v=1645086025\" alt=\"\" class=\"wp-image-110370\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272979172_5071596162884426_4731551265188371262_n-300x242.jpg?v=1645086025 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272979172_5071596162884426_4731551265188371262_n-768x619.jpg?v=1645086025 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272979172_5071596162884426_4731551265188371262_n-1536x1238.jpg?v=1645086025 1536w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272979172_5071596162884426_4731551265188371262_n-1200x967.jpg?v=1645086025 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272979172_5071596162884426_4731551265188371262_n-scaled.jpg?v=1645086025 800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"197\" data-id=\"110371\" src=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272898387_5071595889551120_4685972067265492766_n-300x197.jpg?v=1645086028\" alt=\"\" class=\"wp-image-110371\" srcset=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272898387_5071595889551120_4685972067265492766_n-300x197.jpg?v=1645086028 300w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272898387_5071595889551120_4685972067265492766_n-768x505.jpg?v=1645086028 768w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272898387_5071595889551120_4685972067265492766_n-1536x1010.jpg?v=1645086028 1536w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272898387_5071595889551120_4685972067265492766_n-1200x789.jpg?v=1645086028 1200w, https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272898387_5071595889551120_4685972067265492766_n-scaled.jpg?v=1645086028 800w\" sizes=\"auto, (max-width: 300px) 85vw, 300px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>AUTOR: Juan Carlos Santiago Guinea GABIONES. Fortificaciones de campa\u00f1a.Remontandose su uso al 3000 ADC y siendo inicialmente aplicado en construcciones de arquitectura civil, el empleo de los gabiones (*) como elementos de protecci\u00f3n militar de la artilleria en campa\u00f1a como en fortificaciones defensivas o de asedio comienza a hacerse extensivo con la llegada de la &hellip; <a href=\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/\" class=\"more-link\">Continuar leyendo<span class=\"screen-reader-text\"> &#8220;FABRICACI\u00d3N DE GABIONES&#8221;<\/span><\/a><\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-110226","post","type-post","status-publish","format-standard","hentry","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FABRICACI\u00d3N DE GABIONES - El mundo de los soldaditos de plomo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FABRICACI\u00d3N DE GABIONES - El mundo de los soldaditos de plomo\" \/>\n<meta property=\"og:description\" content=\"AUTOR: Juan Carlos Santiago Guinea GABIONES. Fortificaciones de campa\u00f1a.Remontandose su uso al 3000 ADC y siendo inicialmente aplicado en construcciones de arquitectura civil, el empleo de los gabiones (*) como elementos de protecci\u00f3n militar de la artilleria en campa\u00f1a como en fortificaciones defensivas o de asedio comienza a hacerse extensivo con la llegada de la &hellip; Continuar leyendo &quot;FABRICACI\u00d3N DE GABIONES&quot;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/\" \/>\n<meta property=\"og:site_name\" content=\"El mundo de los soldaditos de plomo\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/El-mundo-de-los-soldaditos-de-plomo-943145209407047\/?modal=admin_todo_tour\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-05T21:05:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-17T08:26:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n-300x239.jpg?v=1645086014\" \/>\n<meta name=\"author\" content=\"Pedro Macanas\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Pedro Macanas\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/\"},\"author\":{\"name\":\"Pedro Macanas\",\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/#\/schema\/person\/692a8bd8346b8870922c57ca6a28ddfb\"},\"headline\":\"FABRICACI\u00d3N DE GABIONES\",\"datePublished\":\"2022-02-05T21:05:53+00:00\",\"dateModified\":\"2022-02-17T08:26:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/\"},\"wordCount\":519,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/#organization\"},\"image\":{\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n-300x239.jpg?v=1645086014\",\"articleSection\":[\"Uncategorized\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/\",\"url\":\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/\",\"name\":\"FABRICACI\u00d3N DE GABIONES - El mundo de los soldaditos de plomo\",\"isPartOf\":{\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n-300x239.jpg?v=1645086014\",\"datePublished\":\"2022-02-05T21:05:53+00:00\",\"dateModified\":\"2022-02-17T08:26:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#primaryimage\",\"url\":\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n.jpg?v=1645086014\",\"contentUrl\":\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n.jpg?v=1645086014\",\"width\":520,\"height\":415},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/lossoldaditosdeplomo.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FABRICACI\u00d3N DE GABIONES\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/#website\",\"url\":\"https:\/\/lossoldaditosdeplomo.com\/\",\"name\":\"El mundo de los soldaditos de plomo\",\"description\":\"coleccionismo, pintura y restauraci\u00f3n soldaditos de plomo\",\"publisher\":{\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/#organization\"},\"alternateName\":\"los soldaditos de plomo\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/lossoldaditosdeplomo.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/#organization\",\"name\":\"El Mundo de los soldaditos de plomo\",\"alternateName\":\"los soldaditos de plomo\",\"url\":\"https:\/\/lossoldaditosdeplomo.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2018\/11\/cropped-IMG_0475-3.jpg\",\"contentUrl\":\"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2018\/11\/cropped-IMG_0475-3.jpg\",\"width\":391,\"height\":533,\"caption\":\"El Mundo de los soldaditos de plomo\"},\"image\":{\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/El-mundo-de-los-soldaditos-de-plomo-943145209407047\/?modal=admin_todo_tour\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/#\/schema\/person\/692a8bd8346b8870922c57ca6a28ddfb\",\"name\":\"Pedro Macanas\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/lossoldaditosdeplomo.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/0c1dfe13db6c04b263e84943daaf93e2d01a188e776e7453456bff2b9793cdb9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/0c1dfe13db6c04b263e84943daaf93e2d01a188e776e7453456bff2b9793cdb9?s=96&d=mm&r=g\",\"caption\":\"Pedro Macanas\"},\"sameAs\":[\"https:\/\/lossoldaditosdeplomo.com\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FABRICACI\u00d3N DE GABIONES - El mundo de los soldaditos de plomo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/","og_locale":"es_ES","og_type":"article","og_title":"FABRICACI\u00d3N DE GABIONES - El mundo de los soldaditos de plomo","og_description":"AUTOR: Juan Carlos Santiago Guinea GABIONES. Fortificaciones de campa\u00f1a.Remontandose su uso al 3000 ADC y siendo inicialmente aplicado en construcciones de arquitectura civil, el empleo de los gabiones (*) como elementos de protecci\u00f3n militar de la artilleria en campa\u00f1a como en fortificaciones defensivas o de asedio comienza a hacerse extensivo con la llegada de la &hellip; Continuar leyendo \"FABRICACI\u00d3N DE GABIONES\"","og_url":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/","og_site_name":"El mundo de los soldaditos de plomo","article_publisher":"https:\/\/www.facebook.com\/El-mundo-de-los-soldaditos-de-plomo-943145209407047\/?modal=admin_todo_tour","article_published_time":"2022-02-05T21:05:53+00:00","article_modified_time":"2022-02-17T08:26:19+00:00","og_image":[{"url":"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n-300x239.jpg?v=1645086014","type":"","width":"","height":""}],"author":"Pedro Macanas","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Pedro Macanas","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#article","isPartOf":{"@id":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/"},"author":{"name":"Pedro Macanas","@id":"https:\/\/lossoldaditosdeplomo.com\/#\/schema\/person\/692a8bd8346b8870922c57ca6a28ddfb"},"headline":"FABRICACI\u00d3N DE GABIONES","datePublished":"2022-02-05T21:05:53+00:00","dateModified":"2022-02-17T08:26:19+00:00","mainEntityOfPage":{"@id":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/"},"wordCount":519,"commentCount":0,"publisher":{"@id":"https:\/\/lossoldaditosdeplomo.com\/#organization"},"image":{"@id":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#primaryimage"},"thumbnailUrl":"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n-300x239.jpg?v=1645086014","articleSection":["Uncategorized"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/","url":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/","name":"FABRICACI\u00d3N DE GABIONES - El mundo de los soldaditos de plomo","isPartOf":{"@id":"https:\/\/lossoldaditosdeplomo.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#primaryimage"},"image":{"@id":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#primaryimage"},"thumbnailUrl":"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n-300x239.jpg?v=1645086014","datePublished":"2022-02-05T21:05:53+00:00","dateModified":"2022-02-17T08:26:19+00:00","breadcrumb":{"@id":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#primaryimage","url":"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n.jpg?v=1645086014","contentUrl":"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2022\/02\/272983524_5071612732882769_8343617857098025346_n.jpg?v=1645086014","width":520,"height":415},{"@type":"BreadcrumbList","@id":"https:\/\/lossoldaditosdeplomo.com\/index.php\/2022\/02\/05\/fabricacion-de-gabiones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/lossoldaditosdeplomo.com\/"},{"@type":"ListItem","position":2,"name":"FABRICACI\u00d3N DE GABIONES"}]},{"@type":"WebSite","@id":"https:\/\/lossoldaditosdeplomo.com\/#website","url":"https:\/\/lossoldaditosdeplomo.com\/","name":"El mundo de los soldaditos de plomo","description":"coleccionismo, pintura y restauraci\u00f3n soldaditos de plomo","publisher":{"@id":"https:\/\/lossoldaditosdeplomo.com\/#organization"},"alternateName":"los soldaditos de plomo","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lossoldaditosdeplomo.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/lossoldaditosdeplomo.com\/#organization","name":"El Mundo de los soldaditos de plomo","alternateName":"los soldaditos de plomo","url":"https:\/\/lossoldaditosdeplomo.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lossoldaditosdeplomo.com\/#\/schema\/logo\/image\/","url":"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2018\/11\/cropped-IMG_0475-3.jpg","contentUrl":"https:\/\/lossoldaditosdeplomo.com\/wp-content\/uploads\/2018\/11\/cropped-IMG_0475-3.jpg","width":391,"height":533,"caption":"El Mundo de los soldaditos de plomo"},"image":{"@id":"https:\/\/lossoldaditosdeplomo.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/El-mundo-de-los-soldaditos-de-plomo-943145209407047\/?modal=admin_todo_tour"]},{"@type":"Person","@id":"https:\/\/lossoldaditosdeplomo.com\/#\/schema\/person\/692a8bd8346b8870922c57ca6a28ddfb","name":"Pedro Macanas","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/lossoldaditosdeplomo.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/0c1dfe13db6c04b263e84943daaf93e2d01a188e776e7453456bff2b9793cdb9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0c1dfe13db6c04b263e84943daaf93e2d01a188e776e7453456bff2b9793cdb9?s=96&d=mm&r=g","caption":"Pedro Macanas"},"sameAs":["https:\/\/lossoldaditosdeplomo.com"]}]}},"_links":{"self":[{"href":"https:\/\/lossoldaditosdeplomo.com\/index.php\/wp-json\/wp\/v2\/posts\/110226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lossoldaditosdeplomo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/lossoldaditosdeplomo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/lossoldaditosdeplomo.com\/index.php\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/lossoldaditosdeplomo.com\/index.php\/wp-json\/wp\/v2\/comments?post=110226"}],"version-history":[{"count":0,"href":"https:\/\/lossoldaditosdeplomo.com\/index.php\/wp-json\/wp\/v2\/posts\/110226\/revisions"}],"wp:attachment":[{"href":"https:\/\/lossoldaditosdeplomo.com\/index.php\/wp-json\/wp\/v2\/media?parent=110226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/lossoldaditosdeplomo.com\/index.php\/wp-json\/wp\/v2\/categories?post=110226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/lossoldaditosdeplomo.com\/index.php\/wp-json\/wp\/v2\/tags?post=110226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}